{"id":10567,"date":"2023-02-28T21:50:07","date_gmt":"2023-02-28T20:50:07","guid":{"rendered":"https:\/\/rasenroboterplanet.com\/?page_id=10567"},"modified":"2023-03-02T06:51:07","modified_gmt":"2023-03-02T05:51:07","slug":"impressum","status":"publish","type":"page","link":"https:\/\/rasenroboterplanet.com\/index.php\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10567\" class=\"elementor elementor-10567\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-94468a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94468a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7125787\" data-id=\"7125787\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e45b1b2 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"e45b1b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Angaben gem\u00e4\u00df \u00a7 5 TMG<\/h2><p>MotorLand GmbH Co. KG<br \/>Schleswig-Holstein, Oldenburg.<\/p><h2>Kontakt<\/h2><p>E-Mail: info@rasenroboterplanet.com<\/p><h2>EU-Streitschlichtung<\/h2><p>Die Europ\u00e4ische Kommission stellt eine Plattform zur Online-Streitbeilegung (OS) bereit:\u00a0<a href=\"https:\/\/ec.europa.eu\/consumers\/odr\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/ec.europa.eu\/consumers\/odr<\/a>.<br \/>Unsere E-Mail-Adresse finden Sie oben im Impressum.<\/p><h2>Verbraucher\u00adstreit\u00adbeilegung\/ Universal\u00adschlichtungs\u00adstelle<\/h2><p>Wir sind nicht bereit oder verpflichtet, an Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teilzunehmen.<\/p><h2>Haftung f\u00fcr Inhalte<\/h2><p>Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind wir als Diensteanbieter jedoch nicht verpflichtet, \u00fcbermittelte oder gespeicherte fremde Informationen zu \u00fcberwachen oder nach Umst\u00e4nden zu forschen, die auf eine rechtswidrige T\u00e4tigkeit hinweisen.<\/p><p>Verpflichtungen zur Entfernung oder Sperrung der Nutzung von Informationen nach den allgemeinen Gesetzen bleiben hiervon unber\u00fchrt. Eine diesbez\u00fcgliche Haftung ist jedoch erst ab dem Zeitpunkt der Kenntnis einer konkreten Rechtsverletzung m\u00f6glich. Bei Bekanntwerden von entsprechenden Rechtsverletzungen werden wir diese Inhalte umgehend entfernen.<\/p><h2>Haftung f\u00fcr Links<\/h2><p>Unser Angebot enth\u00e4lt Links zu externen Websites Dritter, auf deren Inhalte wir keinen Einfluss haben. Deshalb k\u00f6nnen wir f\u00fcr diese fremden Inhalte auch keine Gew\u00e4hr \u00fcbernehmen. F\u00fcr die Inhalte der verlinkten Seiten ist stets der jeweilige Anbieter oder Betreiber der Seiten verantwortlich. Die verlinkten Seiten wurden zum Zeitpunkt der Verlinkung auf m\u00f6gliche Rechtsverst\u00f6\u00dfe \u00fcberpr\u00fcft. Rechtswidrige Inhalte waren zum Zeitpunkt der Verlinkung nicht erkennbar.<\/p><p>Eine permanente inhaltliche Kontrolle der verlinkten Seiten ist jedoch ohne konkrete Anhaltspunkte einer Rechtsverletzung nicht zumutbar. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Links umgehend entfernen.<\/p><h2>Urheberrecht<\/h2><p>Die durch die Seitenbetreiber erstellten Inhalte und Werke auf diesen Seiten unterliegen dem deutschen Urheberrecht. Die Vervielf\u00e4ltigung, Bearbeitung, Verbreitung und jede Art der Verwertung au\u00dferhalb der Grenzen des Urheberrechtes bed\u00fcrfen der schriftlichen Zustimmung des jeweiligen Autors bzw. Erstellers. Downloads und Kopien dieser Seite sind weder f\u00fcr den privaten, noch den kommerziellen Gebrauch gestattet.<\/p><p>Soweit die Inhalte auf dieser Seite nicht vom Betreiber erstellt wurden, werden die Urheberrechte Dritter beachtet. Insbesondere werden Inhalte Dritter als solche gekennzeichnet. Sollten Sie trotzdem auf eine Urheberrechtsverletzung aufmerksam werden, bitten wir um einen entsprechenden Hinweis. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Inhalte umgehend entfernen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Angaben gem\u00e4\u00df \u00a7 5 TMG MotorLand GmbH Co. KG Schleswig-Holstein, Oldenburg. Kontakt E-Mail: info@rasenroboterplanet.com EU-Streitschlichtung Die Europ\u00e4ische Kommission stellt eine<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10567","page","type-page","status-publish","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/rasenroboterplanet.com\/index.php\/wp-json\/wp\/v2\/pages\/10567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rasenroboterplanet.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rasenroboterplanet.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rasenroboterplanet.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rasenroboterplanet.com\/index.php\/wp-json\/wp\/v2\/comments?post=10567"}],"version-history":[{"count":13,"href":"https:\/\/rasenroboterplanet.com\/index.php\/wp-json\/wp\/v2\/pages\/10567\/revisions"}],"predecessor-version":[{"id":10673,"href":"https:\/\/rasenroboterplanet.com\/index.php\/wp-json\/wp\/v2\/pages\/10567\/revisions\/10673"}],"wp:attachment":[{"href":"https:\/\/rasenroboterplanet.com\/index.php\/wp-json\/wp\/v2\/media?parent=10567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}